{"id":381,"date":"2018-11-08T17:33:57","date_gmt":"2018-11-08T16:33:57","guid":{"rendered":"http:\/\/blog.cfpco.fr\/?p=381"},"modified":"2018-11-13T13:25:10","modified_gmt":"2018-11-13T12:25:10","slug":"le-parasympathique-sacre-naissance-de-lanatomie-dun-mythe","status":"publish","type":"post","link":"https:\/\/blog.cfpco.fr\/index.php\/2018\/11\/08\/le-parasympathique-sacre-naissance-de-lanatomie-dun-mythe\/","title":{"rendered":"Le parasympathique sacr\u00e9\u00a0: naissance de l\u2019anatomie d\u2019un mythe."},"content":{"rendered":"<p>Vous avez probablement tous appris comme moi que le syst\u00e8me nerveux neurov\u00e9g\u00e9tatif qui participe \u00e0 la gestion de notre hom\u00e9ostasie est compos\u00e9 en deux syst\u00e8mes antagonistes et compl\u00e9mentaires\u00a0: la composante orthosympathique et la composante para sympathique.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-2231\" src=\"https:\/\/gestiondeladouleurenthrapiemanuelle.files.wordpress.com\/2018\/11\/sna8.png\" alt=\"SNA8\" width=\"568\" height=\"468\" \/><\/p>\n<p>Isabel Espinoza Medina a fait sa th\u00e8se publi\u00e9e en 2017 sur le d\u00e9veloppement des syst\u00e8mes nerveux parasympathique, ent\u00e9rique et sacr\u00e9. Elle a explor\u00e9 les diff\u00e9rentes migrations et interactions neuronales et d\u00e9pendances mol\u00e9culaires lors de la neurog\u00e9n\u00e8se du SNA. A la suite de ces travaux elle propose un r\u00e9examen du syst\u00e8me nerveux sacr\u00e9, qui r\u00e9gule les fonctions urinaire, digestive et reproductrice.<\/p>\n<p>Ce dernier \u00e9tant consid\u00e9r\u00e9 comme parasympathique depuis plus d&rsquo;un si\u00e8cle, sans argument mol\u00e9culaire.<\/p>\n<p>Elle a publi\u00e9 plusieurs articles \u00e0 ce sujet :<\/p>\n<ul>\n<li>Espinosa-Medina, E. Outin, C. A. Picard, Z. Chettouh, S. Dymecki, G. G. Consalez, E. Coppola, J. F. Brunet, Parasympathetic ganglia derive from Schwann cell precursors. Science 345, 87\u201390 (2014).<\/li>\n<li>Espinosa-Medina, O. Saha, F. Boismoreau, Z. Chettouh, F. Rossi, W. D. Richardson and J.-F. Brunet The sacral autonomic outflow is sympathetic Science 354 (6314), 893-897 (2016).<\/li>\n<li>Espinosa-Medina, O. Saha, F. Boismoreau and J.-F. Brunet The \u201csacral parasympathetic\u201d: ontogeny and anatomy of a myth. Clin Auton Res (2018) 28:13\u201321<\/li>\n<\/ul>\n<p>Depuis une \u00e9quipe d&rsquo;expert s&rsquo;acharne a critiquer ses travaux (J\u00e4nig et al 2016, J\u00e4nig et al 2017 2 fois !! \u00a0J\u00e4nig et al 2018) et les d\u00e9bats font du bruit dans Landerneau !!!<\/p>\n<p>Le billet de blog suivant r\u00e9sume et expose essentiellement les travaux d&rsquo;Espinoza et son point de vue qui r\u00e9pond aux diff\u00e9rentes critiques de l&rsquo;\u00e9quipe de J\u00e4nig.<\/p>\n<p>Quand on passe les d\u00e9tails des centres supra-segmentaires (hypothalamus et syst\u00e8me limbique) et des aff\u00e9rences du SNA, et que l\u2019on se penche uniquement sur les neurones effecteurs pr\u00e9-ganglionaires du syst\u00e8me nerveux central, nous avons appris que ceux-ci provenaient (figure ci-dessus) :<\/p>\n<ul>\n<li>De la corne inter-m\u00e9dio-lat\u00e9rale de la moelle de C8 \u00e0 L2 pour le syst\u00e8me orthosympathique (en rouge sur la figure) ;<\/li>\n<li>Des noyaux du tronc c\u00e9r\u00e9bral (II, VII, IX et X) et de la corne inter-m\u00e9dio-lat\u00e9rale de la moelle de S2 \u00e0 S4 pour le syst\u00e8me parasympathique (en vert sur la figure).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<blockquote><p>L&rsquo;affectation de cet influx autonome sacr\u00e9 \u00e0 la division parasympathique du syst\u00e8me nerveux visc\u00e9ral comme 2\u00b0 sortie du parasympathique a \u00e9t\u00e9 propos\u00e9 par Langley en 1899 \u00ab\u00a0de mani\u00e8re remarquablement superficielle, avec une br\u00e8ve justification\u00a0suivie d\u2019une r\u00e9affirmation dans 2 articles en 1905\u00a0et 1911\u00a0\u00bb et depuis cela n\u2019a jamais \u00e9t\u00e9 contredit (Espinoza 2018).<\/p><\/blockquote>\n<table>\n<tbody>\n<tr>\n<td width=\"453\">A tel point que l\u2019on a consid\u00e9r\u00e9 le plexus hypogastique inf\u00e9rieur\/ganglion pelvien (PG sur la photo) comme mixte, un cas unique \u00e0 l\u2019\u00e9poque pour un ganglion du SNA.<\/p>\n<p>Celui-ci est mixte car il re\u00e7oit des entr\u00e9es thoraco-lombaires (par les nerfs hypogastriques) \u00a0et sacr\u00e9es (par les nerfs pelviens NP sur la photos ou nerfs splanchniques pelviens ).<\/td>\n<td width=\"150\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-2226\" src=\"https:\/\/gestiondeladouleurenthrapiemanuelle.files.wordpress.com\/2018\/11\/sna1.png\" alt=\"SNA1\" width=\"258\" height=\"325\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Un des exemples flagrant de l\u2019obscurantisme concernant la non remise en question des assertions de Langley est la r\u00e9pr\u00e9sentation du ganglion pelvien (ou plexus hypogastique inf\u00e9rieur) : ce\u00a0ganglion et\/ou sa connection orthosympathique ont \u00e9t\u00e9 omis des sch\u00e9mas anatomiques par les auteurs les plus connus (Gaskell, Testut, m\u00eame le Gray\u2019s anatomie) \u00a0dans le domaine\u00a0:<\/p>\n<p>Ci-dessous on peut voir comment on a, soit consid\u00e9r\u00e9 ce ganglion uniquement comme relais parasympathique, soit le ganglion n\u2019est m\u00eame pas repr\u00e9sent\u00e9.<\/p>\n<p>Figures en provenance de l\u2019article d\u2019Espinosa et al 2018\u00a0:<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-387\" src=\"http:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA2.png\" alt=\"\" width=\"268\" height=\"314\" srcset=\"https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA2.png 268w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA2-256x300.png 256w\" sizes=\"(max-width: 268px) 100vw, 268px\" \/> <img loading=\"lazy\" class=\"alignleft size-full wp-image-388\" src=\"http:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA3.png\" alt=\"\" width=\"481\" height=\"297\" srcset=\"https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA3.png 481w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA3-300x185.png 300w\" sizes=\"(max-width: 481px) 100vw, 481px\" \/> <img loading=\"lazy\" class=\"alignleft size-full wp-image-389\" src=\"http:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA4.png\" alt=\"\" width=\"481\" height=\"329\" srcset=\"https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA4.png 481w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA4-300x205.png 300w\" sizes=\"(max-width: 481px) 100vw, 481px\" \/> <img loading=\"lazy\" class=\"alignleft size-full wp-image-390\" src=\"http:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA5.png\" alt=\"\" width=\"470\" height=\"200\" srcset=\"https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA5.png 470w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA5-300x128.png 300w\" sizes=\"(max-width: 470px) 100vw, 470px\" \/><\/p>\n\n<p>On peut remarquer sur le sch\u00e9ma de Gaskell (figue b) qu\u2019il repr\u00e9sente les neurones post-ganglionnaires de la m\u00eame fa\u00e7on pour le nerf vague que pour les nerfs splanchniques pelviens, comme si il avait voulu coll\u00e9 l\u2019id\u00e9e d\u2019un \u00ab\u00a0nerf vague pelvien\u00a0\u00bb.<\/p>\n<blockquote><p>Espinosa et al 2018, apporte des \u00e9l\u00e9ments et contre \u00e9l\u00e9ments de r\u00e9flexions <strong>anatomiques, physiologiques, pharmacologiques et g\u00e9n\u00e9tiques<\/strong>, en faveur ou non d\u2019un parasympathique sacr\u00e9 d\u2019origine m\u00e9dullaire.<\/p><\/blockquote>\n<h2>D\u2019un point de vue anatomique\u00a0:<\/h2>\n<ol>\n<li>Le trou de zone interm\u00e9diolat\u00e9rale au niveau lombaire pose une question qui a servi de support au fait de dire que la moelle sacr\u00e9e \u00e9tait du parasympathique. Cet argument n\u2019est pas suffisant et peut tr\u00e8s bien se comprendre d\u2019un point de vue de l\u2019\u00e9volution\u00a0: avec la station debout et la n\u00e9cessit\u00e9 de locomotion, un \u00e9puisement ontog\u00e9n\u00e9tique de neurones pr\u00e9ganglionnaires lombaires et sacr\u00e9 a tr\u00e8s bien pu se faire en faveur des motoneurones pour le membre inf\u00e9rieur (ces nerfs proviennent des m\u00eames pr\u00e9curseurs embryologiques).<\/li>\n<li>L\u2019absence de rameau communicant blanc (par lequel passent les aff\u00e9rences et l\u2019efference pr\u00e9ganglionnaire orthosympathique) au niveau lombaire bas et sacr\u00e9 avec la chaine lat\u00e9rovert\u00e9brale.<\/li>\n<\/ol>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-391\" src=\"http:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA6.png\" alt=\"\" width=\"443\" height=\"1200\" srcset=\"https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA6.png 443w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA6-300x813.png 300w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA6-111x300.png 111w, https:\/\/blog.cfpco.fr\/wp-content\/uploads\/2018\/11\/SNA6-378x1024.png 378w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><\/p>\n<p>Il n\u2019existe pas non plus ces rameaux communicants au niveau cervical (ou il y a des ganglions cervicaux) et le ganglion pelvien pourrait tr\u00e8s bien \u00eatre consid\u00e9r\u00e9 par analogie \u00e0 un ganglion cervical inf\u00e9rieur.<\/p>\n<p>A contrario d\u2019un point de vue anatomique\u00a0:<\/p>\n<ol>\n<li>Au d\u00e9part du tronc c\u00e9r\u00e9bral tous les <strong>points de sorties du syst\u00e8me parasympathique sont post\u00e9rolat\u00e9rales<\/strong>, alors que dans la moelle <em>efferences neurov\u00e9g\u00e9tatives thoracolombaires et sacr\u00e9s sont ventrales<\/em>(par la branche ant\u00e9rieures du nerf spinal);<\/li>\n<li>Sur le trajet autonome sacr\u00e9 vers l&rsquo;intestin, les partenaires pr\u00e9synaptiques des neurones ent\u00e9riques se trouvent dans le syst\u00e8me nerveux p\u00e9riph\u00e9rique (dans les ganglions pelviens), tout comme sur la voie thoraco-lombaire (dans les ganglions m\u00e9sent\u00e9riques), tandis que sur la voie cr\u00e2nienne, ils se trouvent dans le syst\u00e8me nerveux central (dans le noyau moteur dorsal du nerf vague):<\/li>\n<li>Un certain nombre de neurones ganglionnaires pelviens individuels re\u00e7oivent une double innervation lombo-sacr\u00e9e tout comme le font les neurones ganglionnaires m\u00e9sent\u00e9riques inf\u00e9rieurs.<\/li>\n<\/ol>\n<blockquote><p>Il n&rsquo;y a pas d&rsquo;argument anatomique en faveur d&rsquo;une justification d&rsquo;un syst\u00e8me parasympathique \u00ab\u00a0cranio-sacr\u00e9\u00a0\u00bb<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2>D\u2019un point de vue pharmacologique\u00a0:<\/h2>\n<p>Le syst\u00e8me parasympathique a \u00e9t\u00e9 d\u00e9crit comme cholinergique car le neurotransmetteur effectif est l\u2019acetylcholine qui se fixe sur des r\u00e9cepteurs muscariniques au niveau des organes cibles.<\/p>\n<p>Le syst\u00e8me sympathique a \u00e9t\u00e9 d\u00e9crit comme adr\u00e9nergique car le neurotransmetteur effectif est la noradr\u00e9naline au niveau des organes cibles.<\/p>\n<p>La sensibilit\u00e9 des \u00absubstances r\u00e9ceptives\u00bb aux agonistes et aux antagonistes a jou\u00e9 un r\u00f4le majeur dans la consolidation de la proposition de Langley comme quoi le syst\u00e8me parasympathique cranio-sacr\u00e9 ne soit qu\u2019un seul et m\u00eame syst\u00e8me\u00a0: la pilocarpine (agoniste des r\u00e9cepteurs muscariniques) imite plusieurs r\u00e9actions physiologiques \u00e0 la stimulation des nerfs splachniques pelviens (comme la salivation ou le myosis), refl\u00e9tant le fait que les ganglions pelviens contiennent de nombreux neurones cholinergiques.<\/p>\n<p>Sauf que\u00a0:<\/p>\n<ol>\n<li>Depuis 1934 (Dale et Feldberg) on sait que l<strong>e syst\u00e8me orthosympathique a aussi des r\u00e9cepteurs muscariniques qui r\u00e9agissent \u00e0 l\u2019acetylcholine<\/strong>(notamment dans les glandes sudoripares, la pilocarpine fait transpirer).<\/li>\n<li><strong>Tous les neurones pr\u00e9ganglionaires du SNA sont sous d\u00e9pendance de l\u2019ac\u00e9tylcholine<\/strong>(r\u00e9cepteurs muscarinique ou nicotinique pour le sympathique et uniquement muscarinique pour le parasympathique)<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>Donc la pr\u00e9sence de neurones cholinergiques dans les nerfs splanchniques pelviens n\u2019est pas une preuve qu\u2019ils sont de fonction parasympathique.<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2>D\u2019un point de vue physiologique\u00a0:<\/h2>\n<h3>A propos de la miction\u00a0:<\/h3>\n<p>Un des arguments cit\u00e9 est par Langley et d\u2019autres, est la fonction l&rsquo;antagonisme lombo-sacr\u00e9 sur le muscle detrusor de la vessie et en particulier l\u2019inhibition sympathique lombaire. En l\u2019occurrence aucune exp\u00e9rimentation jusqu&rsquo;\u00e0 ce jour n\u2019a prouv\u00e9 son existence, ni m\u00eame la pr\u00e9sence de fibre sympathique dans le muscle d\u00e9trusor (Espinosa et al 2018).<\/p>\n<p>Au contraire il a \u00e9t\u00e9 d\u00e9montr\u00e9 que le <strong>bloc de conduction sur le syst\u00e8me sympathique<\/strong>lombaire chez l&rsquo;homme n&rsquo;a <strong>pas de cons\u00e9quence fonctionnelle sur la miction\u00a0<\/strong>(Folwer et al 2008).<\/p>\n<h3>A propos de l\u2019\u00e9rection\u00a0(tir\u00e9 de la th\u00e8se d\u2019Espinosa 2017):<\/h3>\n<p>\u00ab\u00a0De m\u00eame, la croyance en un antagonisme parasympathique \/ sympathique dans le pelvis a conduit \u00e0 n\u00e9gliger la preuve d&rsquo;un r\u00f4le de la contribution sympathique lombaire dans l&rsquo;\u00e9rection (donc dans la dilatation des vaisseaux sanguins), g\u00e9n\u00e9ralement pr\u00e9sent\u00e9e comme \u00e9tant m\u00e9di\u00e9e exclusivement par les nerfs parasympathiques sacr\u00e9s. En 1979 d\u00e9j\u00e0, Sj\u00f6strand et Klinge affirmaient l&rsquo;<strong>existence de fibres sympathiques hypogastriques participant \u00e0 l\u2019\u00e9rection<\/strong>\u2026\u00a0\u00bb (et dans son article de 2018, Espinosa expose d\u2019autres \u00e9tudes exp\u00e9rimentales d\u00e9montrant que l\u2019\u00e9rection \u00e9tait m\u00e9di\u00e9e \u00e0 travers des voies orthosympathiques cholinergiques)<\/p>\n<p>\u00ab\u00a0\u2026Il existe des preuves d&rsquo;une <strong>synergie des voies lombaires et sacrales de la vasodilatation dans les organes reproducteurs externes<\/strong>(J\u00e4nig, 2006) qui plaide contre un antagonisme entre eux \u2026 et pourtant la plupart des revues maintiennent le dogme de l&rsquo;antagonisme.\u00a0\u00bb<\/p>\n<h2>D\u2019un point de vue g\u00e9n\u00e9tique et mol\u00e9culaire :<\/h2>\n<p>Dans son premier travail Espinosa et al 2014 d\u00e9montre que la \u00ab\u00a0<strong>signature neurale des nerfs parasympathiques cr\u00e2niens<\/strong>provient des <strong>pr\u00e9curseurs des cellules de Schwann<\/strong>(SCPs) qui envahissent les nerfs pr\u00e9ganglionaires jusqu&rsquo;\u00e0 leur destination, proche des organes cibles\u00a0\u00bb.<\/p>\n<p>Elle a fait la m\u00eame chose pour les neurones sympathiques thoraco-lombaires en montrant que c\u2019\u00e9tait une <strong>signature neurale particuli\u00e8re (diff\u00e9rente du parasympathique cr\u00e2nien)<\/strong><\/p>\n<blockquote><p>Dans son second article (Espinosa et al 2016) elle d\u00e9montre que les <strong>neurones en provenance de la zone interm\u00e9diolat\u00e9rale de la moelle sacr\u00e9e<\/strong>ont la m\u00eame signature neurale que les <strong>neurones sympathiques thoraco-lombaires<\/strong>et que les <strong>ganglions pelviens ont une signature transcriptionnelle sympathique<\/strong>et non para-sympathique :<\/p><\/blockquote>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-2240\" src=\"https:\/\/gestiondeladouleurenthrapiemanuelle.files.wordpress.com\/2018\/11\/sna9.png\" alt=\"SNA9\" width=\"943\" height=\"462\" \/><\/p>\n<blockquote><p><strong>Le syst\u00e8me nerveux sacr\u00e9 est en fait sympathique.<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2>En Conclusion\u00a0:<\/h2>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-2233\" src=\"https:\/\/gestiondeladouleurenthrapiemanuelle.files.wordpress.com\/2018\/11\/sna7.png\" alt=\"SNA7\" width=\"906\" height=\"870\" \/><\/p>\n<p>Tout d\u2019abord Espinoza-Medina propose donc une nouvelle organisation du syst\u00e8me nerveux autonome compos\u00e9 de trois divisions contrast\u00e9es par leur <strong>origine embryonnaire aussi bien que par leur anatomie adulte<\/strong>:<\/p>\n<blockquote><p>une <strong>parasympathique<\/strong>d&rsquo;origine et de connectivit\u00e9 exclusivement <strong>cr\u00e2nienne<\/strong>,<\/p><\/blockquote>\n<blockquote><p>une <strong>sympathique spinale<\/strong>, allant de l&rsquo;\u00e9tage<strong>cervical au sacr\u00e9<\/strong>(Espinosa-Medina et al., 2016)<\/p><\/blockquote>\n<blockquote><p>et une division <strong>ent\u00e9rique<\/strong>que son origine aussi bien que sa connectivit\u00e9 placent \u00e0 l&rsquo;<strong>interface des syst\u00e8mes sympathique et parasympathique.<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Au niveau pelvien, la science est en train de d\u00e9chiffrer la complexit\u00e9 du fonctionnement hom\u00e9ostatique (diff\u00e9rents types de cellules et fonctions), et il est claire qu\u2019il n\u2019est pas comparable aux autres visc\u00e8res. Il serait donc illusoire de l\u2019expliquer par fonctions l\u2019antagonisme anatomique parasympathique\/ orthosympathique.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PS : Une remarque sur tous ces travaux d\u2019Espinoza-Medina\u00a0:<\/p>\n<p>Ces \u00e9tudes ont \u00e9t\u00e9 faites sur les rats , et c\u2019est vrai qu\u2019en recherche on commence toujours par l\u2019animal (du plus petit vers le plus gros\u00a0: rat, lapin, chat\u2026cheval..). Les r\u00e9sultats \u00a0de ces travaux sont donc \u00e0 confirmer chez l\u2019homme.<\/p>\n<p>Ceci \u00e9tant\u00a0:<\/p>\n<ol>\n<li>Aucune recherche sur l\u2019humain ni sur l&rsquo;animal n\u2019a \u00e0 ce jour montr\u00e9 que le syst\u00e8me nerveux autonome sacr\u00e9 \u00e9tait parasympathique;<\/li>\n<li>D\u2019autre part une \u00e9quipe fran\u00e7aise (Alsaid et al 2009) a fait un tra\u00e7age immunohistochimique chez des f\u0153tus humain male et a montr\u00e9 dans les nerfs splanchniques pelviens la pr\u00e9sence de fibres cholinergiques et des adr\u00e9nergique (le syst\u00e8me orthosympathique est le seul \u00e0 pr\u00e9senter ces deux types de fibres, le parasympathique n\u2019a que des fibres cholinergique)<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Alsaid B et al. 3D reconstruction of the inferior hypogastric plexus. J. Anat. (2009) 214, pp645\u2013654<\/p>\n<p>Dale HH, Feldberg W (1934) The chemical transmission of secretory impulses to the sweat glands of the cat. J Physiol 82:121\u2013128.<\/p>\n<p>&nbsp;<\/p>\n<p>Espinosa-Medina . On the development of the parasympathetic, enteric and sacral nervous systems. Th\u00e8se de Doctorat de biologie du d\u00e9veloppement. UPMC (2017).<\/p>\n<p>Espinosa-Medina, E. Outin, C. A. Picard, Z. Chettouh, S. Dymecki, G. G. Consalez, E. Coppola, J. F. Brunet, Parasympathetic ganglia derive from Schwann cell precursors. Science 345, 87\u201390 (2014).<\/p>\n<p>Espinosa-Medina, O. Saha, F. Boismoreau, Z. Chettouh, F. Rossi, W. D. Richardson and J.-F. Brunet The sacral autonomic outflow is sympathetic Science 354 (6314), 893-897 (2016).<\/p>\n<p>Espinosa-Medina, O. Saha, F. Boismoreau and J.-F. Brunet The \u201csacral parasympathetic\u201d: ontogeny and anatomy of a myth. Clin Auton Res (2018) 28:13\u201321<\/p>\n<p>Gaskell WH (1920) The involuntary nervous system. Longmans, Green, New York<\/p>\n<p>J\u00e4nig, The Integrative Action of the Autonomic Nervous System: Neurobiology of Homeostatis (Cambridge Univ. Press, Cambridge, UK, 2006).<\/p>\n<p>J\u00e4nig W, Keast J, McLachlan E, Neuhuber W, Southard-Smith M (2016) E-Letter. In: Science<\/p>\n<p>Janig W, Keast JR, McLachlan EM, Neuhuber WL, Southard- Smith M (2017) Renaming all spinal autonomic outflows as sym- pathetic is a mistake. Auton Neurosci 206:60\u201362<\/p>\n<p>Janig W, McLachlan EM, Neuhuber WL (2018) The sacral auto- nomic outflow: against premature oversimplification. Clin Auton Res. <a href=\"https:\/\/doi.org\/10.1007\/s10286-017-0491-x\">https:\/\/doi.org\/10.1007\/s10286-017-0491-x<\/a><\/p>\n<p>Janig W, Neuhuber W (2017) Reclassification of the sacral auto- nomic outflow to pelvic organs as the caudal outpost of the sympa- thetic system is misleading. J Am Osteopath Assoc 117:416\u2013417<\/p>\n<p>Langley JN (1899) Presidential address, physiological section. Report of the 69th meetings of the British Association for the Advancement of Science. John Murray, London, pp 881\u2013892<\/p>\n<p>Langley JN (1905) On the reaction of cells and of nerve-endings to certain poisons, chiefly as regards the reaction of striated muscle to nicotine and to curari. J Physiol 33:374\u2013413<\/p>\n<p>Langley JN (1911) The effect of various poisons upon the response to nervous stimuli chiefly in relation to the bladder. J Physiol 43:125\u2013181. doi:10.1111\/(ISSN)1469-7793<\/p>\n<p>Latarjet A, Testut L (1948) Trait\u00e9 d\u2019anatomie humaine. G. Doin &amp; Cie, Paris<\/p>\n<p>Sj\u00f6strand, N. O. and Klinge, E. \u00ab Principal mechanisms controlling penile retraction and protrusion in rabbits \u00bb. Acta Physiologica Scandinavica. Volume 106, no.2 (June 1979): 199\u2013214.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez probablement tous appris comme moi que le syst\u00e8me nerveux neurov\u00e9g\u00e9tatif qui participe \u00e0 la gestion de notre hom\u00e9ostasie est compos\u00e9 en deux syst\u00e8mes antagonistes et compl\u00e9mentaires\u00a0: la composante orthosympathique et la composante para sympathique. Isabel Espinoza Medina a fait sa th\u00e8se publi\u00e9e en 2017 sur le d\u00e9veloppement des syst\u00e8mes nerveux parasympathique, ent\u00e9rique et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[52,35],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/posts\/381"}],"collection":[{"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":6,"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"predecessor-version":[{"id":395,"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/posts\/381\/revisions\/395"}],"wp:attachment":[{"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cfpco.fr\/index.php\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}